{"id":13969,"date":"2018-02-24T16:00:28","date_gmt":"2018-02-24T15:00:28","guid":{"rendered":"http:\/\/nerdenthum.de\/?p=13969"},"modified":"2018-02-23T16:40:21","modified_gmt":"2018-02-23T15:40:21","slug":"lucifer-3-deu","status":"publish","type":"post","link":"https:\/\/nerdenthum.de\/index.php\/2018\/02\/24\/lucifer-3-deu\/","title":{"rendered":"Lucifer #3 [deu]"},"content":{"rendered":"<p>Der Teufel gegen Die Pr\u00e4senz.<\/p>\n<p><a href=\"http:\/\/nerdenthum.de\/wp-content\/uploads\/2018\/02\/LUCIFERMEINWILLEGESCHEHE3_Softcover_848.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/nerdenthum.de\/wp-content\/uploads\/2018\/02\/LUCIFERMEINWILLEGESCHEHE3_Softcover_848-197x300.jpg\" alt=\"\" width=\"197\" height=\"300\" class=\"alignright size-medium wp-image-13970\" srcset=\"https:\/\/nerdenthum.de\/wp-content\/uploads\/2018\/02\/LUCIFERMEINWILLEGESCHEHE3_Softcover_848-197x300.jpg 197w, https:\/\/nerdenthum.de\/wp-content\/uploads\/2018\/02\/LUCIFERMEINWILLEGESCHEHE3_Softcover_848.jpg 493w\" sizes=\"auto, (max-width: 197px) 100vw, 197px\" \/><\/a><\/p>\n<p><strong>Autor:<\/strong> Holly Black, Richard Kadrey<br \/>\n<strong>Zeichner &#038; Tusche:<\/strong> Lee Garbett, Marco Rudy, Ben Templesmith<br \/>\n<strong>Farben:<\/strong> Antonio Fabela, Marco Rudy, Ben Templesmith<br \/>\n<strong>Letterer:<\/strong> Astarte Design<br \/>\n<strong>\u00dcbersetzung:<\/strong> Gerline Althoff<br \/>\n<strong>Kaufen:<\/strong> <a href=\"https:\/\/www.paninishop.de\/artikel\/dvelu003-lucifer-mein-wille-geschehe-3\" target=\"_blank\">Panini Shop<\/a><br \/>\n<strong>Bewertung:<\/strong> 3\/5<\/p>\n<p>Lucifer hat seine Kr\u00e4fte zur\u00fcck und auch der Mord an &#8222;Gott&#8220; ist aufgekl\u00e4rt doch nun haben die D\u00e4monen und gefallenen Engel um den H\u00f6llenf\u00fcrsten ein anderes Problem. Die aus Gottes Tod wieder auferstandene &#8222;Pr\u00e4senz&#8220; ist alles andere als gut und so bleibt es an den &#8222;B\u00f6sen&#8220; h\u00e4ngen die Menschen zu besch\u00fctzen. <\/p>\n<p>Der Band krankt ein wenig daran das Holly Black ne Menge Figuren eingef\u00fchrt hat und Kadrey nicht nur die aufgreift sondern auch noch neue einf\u00fchrt. So verliert man schonmal leicht den \u00dcberblick dar\u00fcber wer denn nun wer ist und welche Motivation der einzelne hat. Dabei ist es zudem noch problematisch, dass das Artwork die Unterscheidung zwischen einigen nochmal erschwert. <\/p>\n<p>Die Story an sich dreht sich mal wieder um Gut und B\u00f6se, freien Willen, Liebe und Verrat und das alles ist durchaus interessant erz\u00e4hlt. Wenn man die Stellen wo man sich der Charaktere unsicher ist einfach zwei mal liest ist auch das Verst\u00e4ndnis kein Problem. Die Darstellung der &#8222;Pr\u00e4senz&#8220; (dieses Wesen in einem christlichen Kontext tats\u00e4chlich Gott zu neben w\u00e4re grunds\u00e4tzlich falsch) ist durchaus interessant weil sie sich eben auf den Kontrollgedanken abzielt den viele den Christen vorwerfen. <\/p>\n<p>Alles andere ist dennoch wenig \u00fcberraschend und schnell zu durchschauen weil es einem bekannten Muster folgt. Das Luicifer hier der Gute ist wirkt zudem \u00fcbertrieben. Selbst Constantine ist in seinen Serien nicht so gut und mitf\u00fchlend wie der Teufel hier.<\/p>\n<p>Zeichnerisch gibt es das oben beschriebene Problem der \u00c4hnlichkeit der Charaktere, zudem wirken die D\u00e4monen zum Teil eher l\u00e4cherlich als gruselig. Es ist sicher kein Totalausfall und ein Teil der abgedrehteren Szenen sind durchaus gut umgesetzt, aber alles in Allem h\u00e4tte man hier mehr draus machen k\u00f6nnen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Teufel gegen Die Pr\u00e4senz. Autor: Holly Black, Richard Kadrey Zeichner &#038; Tusche: Lee Garbett, Marco Rudy, Ben Templesmith Farben: Antonio Fabela, Marco Rudy, Ben Templesmith Letterer: Astarte Design \u00dcbersetzung: Gerline Althoff Kaufen: Panini Shop Bewertung: 3\/5 Lucifer hat seine Kr\u00e4fte zur\u00fcck und auch der Mord an &#8222;Gott&#8220; ist aufgekl\u00e4rt doch nun haben die D\u00e4monen [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13970,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[121],"tags":[304,481,1785,482,478,479,1784,676,9,1783],"class_list":["post-13969","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-comics-deu","tag-antonio-fabela","tag-astarte-design","tag-ben-templesmith","tag-gerline-althoff","tag-holly-black","tag-lee-garbett","tag-lucifer","tag-marco-rudy","tag-panini","tag-richard-kadrey","post_format-post-format-image"],"_links":{"self":[{"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/posts\/13969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/comments?post=13969"}],"version-history":[{"count":2,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/posts\/13969\/revisions"}],"predecessor-version":[{"id":13972,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/posts\/13969\/revisions\/13972"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/media\/13970"}],"wp:attachment":[{"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/media?parent=13969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/categories?post=13969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/tags?post=13969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}