{"id":18583,"date":"2018-12-13T18:00:30","date_gmt":"2018-12-13T17:00:30","guid":{"rendered":"http:\/\/nerdenthum.de\/?p=18583"},"modified":"2018-12-13T14:27:07","modified_gmt":"2018-12-13T13:27:07","slug":"green-lantern-erde-eins-deu","status":"publish","type":"post","link":"https:\/\/nerdenthum.de\/index.php\/2018\/12\/13\/green-lantern-erde-eins-deu\/","title":{"rendered":"Green Lantern: Erde Eins [deu]"},"content":{"rendered":"<p>Eine Neuinterpretation der anderen Art.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/nerdenthum.de\/wp-content\/uploads\/2018\/12\/green-lantern-erde-eins-softcover-softcover-1537952056.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-18584 size-medium\" src=\"https:\/\/i0.wp.com\/nerdenthum.de\/wp-content\/uploads\/2018\/12\/green-lantern-erde-eins-softcover-softcover-1537952056.jpg?resize=196%2C300\" alt=\"\" width=\"196\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/nerdenthum.de\/wp-content\/uploads\/2018\/12\/green-lantern-erde-eins-softcover-softcover-1537952056.jpg?resize=196%2C300&amp;ssl=1 196w, https:\/\/i0.wp.com\/nerdenthum.de\/wp-content\/uploads\/2018\/12\/green-lantern-erde-eins-softcover-softcover-1537952056.jpg?w=490&amp;ssl=1 490w\" sizes=\"auto, (max-width: 196px) 100vw, 196px\" \/><\/a><\/p>\n<p><strong>Autor:<\/strong> Corinna Bechko, Gabriel Hardman<br \/><strong>Zeichner:<\/strong>\u00a0Gabriel Hardman<br \/><strong>Farben:<\/strong> Jordan Boyd<br \/><strong>Lettering:<\/strong> Walproject<br \/><strong>\u00dcbersetzung:<\/strong> Christian Hei\u00df<br \/><strong>Kaufen:<\/strong> <a href=\"https:\/\/www.paninishop.de\/artikel\/ddcpb128-green-lantern-erde-eins\" target=\"_blank\" rel=\"noopener\">Panini Shop<\/a><br \/><strong>Lesepropbe:<\/strong> <a href=\"http:\/\/www.mycomics.de\/comic-pages\/10874-green-lantern-erde-eins.html#page\/1\/mode\/2up\" target=\"_blank\" rel=\"noopener\">MyComics.de<\/a><\/p>\n<p><strong>Bewertung:<\/strong>\u00a02\/5<\/p>\n<p><!--more--><\/p>\n<p>Die &#8222;Erde Eins&#8220; B\u00e4nde bieten einen frischen Blick auf etablierte Helden und geben ihnen eine neue &#8222;Origin&#8220; die gleicherma\u00dfen f\u00fcr Einsteiger als auch alte Fans interessant sein sollen. Bei Superman, Batman und Wonder Woman hat dies dank erfahrenen Autoren und interessanten Konzepten gut funktioniert, bei Green Lantern leider weniger.<\/p>\n<p>Bisher war im Comic sowie im (zugegebenerma\u00dfen nicht so tollen) Film Hal Jordan ein draufg\u00e4ngerischer Testpilot der in den Besitzt eines Green Lantern Ringes kam und von da an als Weltraumpolizist die Galaxy besch\u00fctzte. Hier jedoch wird die Handlung schon zu Beginn in den Weltraum und auch ein wenig in die Zukunft verlagert. Harold Jordan ist ein Astronaut der f\u00fcr\u00a0 Ferris Galactic auf Asteroiden nach Palladium sch\u00fcrft. Er ist auch nicht so der Draufg\u00e4nger und als er den Ring findet wird es eigentlich noch d\u00fcsterer. Die Handlung ist von Untergang und Bedrohung beherrscht und h\u00e4tte sich vielleicht als Film in Anlehnung zu Alien noch gut gemacht, so jedoch bleibt sie deutlich hinter den Erwartungen zur\u00fcck.\u00a0<\/p>\n<p>Weder Hal noch Kilowog oder Arisia die als Nebencharaktere vorkommen k\u00f6nnen \u00fcberzeugen, die Handlung wirkt sehr generisch und die Zeichnungen sind oftmals so unsauber das man Probleme hat zu erkennen wer wer ist, solange es sich nicht um ein Alien handelt.\u00a0<\/p>\n<p>Insgesamt bleibt der Band weit hinter seinen M\u00f6glichkeiten zur\u00fcck.<\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Eine Neuinterpretation der anderen Art. Autor: Corinna Bechko, Gabriel HardmanZeichner:\u00a0Gabriel HardmanFarben: Jordan BoydLettering: Walproject\u00dcbersetzung: Christian Hei\u00dfKaufen: Panini ShopLesepropbe: MyComics.de Bewertung:\u00a02\/5<\/p>\n","protected":false},"author":1,"featured_media":18584,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[121],"tags":[944,2404,2405,609,9,359],"class_list":["post-18583","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-comics-deu","tag-christian-heiss","tag-corinna-bechko","tag-gabriel-hardman","tag-jordan-boyd","tag-panini","tag-walproject","post_format-post-format-image"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/nerdenthum.de\/wp-content\/uploads\/2018\/12\/green-lantern-erde-eins-softcover-softcover-1537952056.jpg?fit=490%2C750&ssl=1","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/posts\/18583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/comments?post=18583"}],"version-history":[{"count":1,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/posts\/18583\/revisions"}],"predecessor-version":[{"id":18585,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/posts\/18583\/revisions\/18585"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/media\/18584"}],"wp:attachment":[{"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/media?parent=18583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/categories?post=18583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/tags?post=18583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}