{"id":19970,"date":"2019-03-19T12:00:12","date_gmt":"2019-03-19T11:00:12","guid":{"rendered":"http:\/\/nerdenthum.de\/?p=19970"},"modified":"2019-04-01T15:47:58","modified_gmt":"2019-04-01T13:47:58","slug":"batman-der-weisse-ritter-deu","status":"publish","type":"post","link":"https:\/\/nerdenthum.de\/index.php\/2019\/03\/19\/batman-der-weisse-ritter-deu\/","title":{"rendered":"Batman: Der Weisse Ritter [deu]"},"content":{"rendered":"\n<p>Das moderne Bat-Meisterwerk endlich auch auf Deutsch.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><a href=\"https:\/\/i0.wp.com\/nerdenthum.de\/wp-content\/uploads\/2019\/01\/Infinity-Wars-Fallen-Guardian-1.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/nerdenthum.de\/wp-content\/uploads\/2019\/03\/BatmanDerWeisseRitte_342.jpg?resize=196%2C300\" alt=\"\" class=\"wp-image-19971\" width=\"196\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/nerdenthum.de\/wp-content\/uploads\/2019\/03\/BatmanDerWeisseRitte_342.jpg?w=491&amp;ssl=1 491w, https:\/\/i0.wp.com\/nerdenthum.de\/wp-content\/uploads\/2019\/03\/BatmanDerWeisseRitte_342.jpg?resize=196%2C300&amp;ssl=1 196w\" sizes=\"auto, (max-width: 196px) 100vw, 196px\" \/><\/a><\/figure><\/div>\n\n\n\n<p><strong>Autor \/ Zeichner:<\/strong> Sean Murphy<br><strong>Farben:<\/strong> Matt Hollingsworth<br><strong>Letterer:<\/strong> Gianluca Pini<br><strong>\u00dcbersetzung:<\/strong> Josef Rother<br><strong>Kaufen:<\/strong> <a href=\"https:\/\/www.paninishop.de\/artikel\/dblack001-batman-weisse-ritter-softcover\">Panini Shop<\/a><br><strong>Leseprobe:<\/strong> <a href=\"http:\/\/www.mycomics.de\/comic-pages\/11148-batman-der-weisse-ritter.html#page\/1\/mode\/2up\">myComics.de<\/a><br><strong>Bewertung:<\/strong> 5\/5<\/p>\n\n\n\n<p>Unser <a href=\"http:\/\/nerdenthum.de\/index.php\/2019\/03\/10\/gewinnspiel-batman-der-weisse-ritter\/\">Gewinnspiel<\/a> zu diesem Band l\u00e4uft noch bis zum 24.3.2019.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Was w\u00e4re wenn der Joker nicht mehr verr\u00fcckt w\u00e4re? Was wenn er den Wahnsinn zur\u00fcck lassen k\u00f6nnte und f\u00fcr Gotham der Weise Ritter sein k\u00f6nnte? Was wenn in all dem Batman einen Schritt zu weit geht, zu brutal und r\u00fccksichtslos wird?<\/p>\n\n\n\n<p>Sean Murphy pr\u00e4sentiert und hier Jack Napier, der Mann der vorher Joker war und nun nach und nach gegen Korruption und Brutalit\u00e4t k\u00e4mpft. Doch dies ist weit davon entfernt ein echter Rollertausch zu sein. Die Ver\u00e4nderungen sind gr\u00f6\u00dftenteils viel subtile was den gr\u00f6\u00dften Reiz des Bandes ausmacht, da man eben nie genau wei\u00df wer nun der Gute ist und wer der B\u00f6se, wer im Recht ist und wer nun tats\u00e4chlich aufgehalten werden sollte.<\/p>\n\n\n\n<p>Es sind auch die vielen kleinen Dinge die den Band weit \u00fcber das Pr\u00e4dikat &#8222;Lesenswert&#8220; hinaus katapultieren. Andere Schurken finden sich auf die eine oder andere Art hier wieder und auch die Familie rund um den dunklen Ritter taucht auf. Interessant ist auch die Erkl\u00e4rung warum Harley Quinn so pl\u00f6tzlich ihr Design und ihr Auftreten ge\u00e4ndert hat.<\/p>\n\n\n\n<p>Zudem merkt man Murphys Liebe zu Fahrzeugen. Es tauchen alle m\u00f6glichen Batmobile auf. Sei es der &#8222;Tumbler&#8220; aus den Nolan Filmen oder die &#8222;Turbine&#8220; aus dem Tim Burton Film. Dabei sind die nicht nur schm\u00fcckendes Beiwerk sondern ein zentraler Gegenstand der Geschichte.<\/p>\n\n\n\n<p>Aber nicht nur die Geschichte ist bis ins kleinste Detail ein Meisterwerk, auch die dazu passenden Zeichnungen heben diesen Band weit \u00fcber das hinaus was man aktuell schon an genialen Batman Geschichten geboten bekommt. Nicht nur die Liebe zum Detail bei den Fahrzeugen, auch das ganze Design von Gotham, die Architektur und vor allem die Charaktere die  auch in Kleinigkeiten immer wieder extrem stimmig sind \u00fcberzeugen. <\/p>\n\n\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das moderne Bat-Meisterwerk endlich auch auf Deutsch. Autor \/ Zeichner: Sean MurphyFarben: Matt HollingsworthLetterer: Gianluca Pini\u00dcbersetzung: Josef RotherKaufen: Panini ShopLeseprobe: myComics.deBewertung: 5\/5 Unser Gewinnspiel zu diesem Band l\u00e4uft noch bis zum 24.3.2019.<\/p>\n","protected":false},"author":1,"featured_media":19971,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[121],"tags":[290,365,9,2264,1651,2263],"class_list":["post-19970","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-comics-deu","tag-batman","tag-matt-hollingsworth","tag-panini","tag-sean-murphy","tag-todd-klein","tag-white-knight","post_format-post-format-image"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/nerdenthum.de\/wp-content\/uploads\/2019\/03\/BatmanDerWeisseRitte_342.jpg?fit=491%2C750&ssl=1","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/posts\/19970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/comments?post=19970"}],"version-history":[{"count":2,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/posts\/19970\/revisions"}],"predecessor-version":[{"id":20156,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/posts\/19970\/revisions\/20156"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/media\/19971"}],"wp:attachment":[{"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/media?parent=19970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/categories?post=19970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/tags?post=19970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}