{"id":21762,"date":"2019-07-23T13:00:26","date_gmt":"2019-07-23T11:00:26","guid":{"rendered":"http:\/\/nerdenthum.de\/?p=21762"},"modified":"2019-07-23T10:02:58","modified_gmt":"2019-07-23T08:02:58","slug":"der-us-comicmarkt-2018-buchhandel","status":"publish","type":"post","link":"https:\/\/nerdenthum.de\/index.php\/2019\/07\/23\/der-us-comicmarkt-2018-buchhandel\/","title":{"rendered":"Der US Comicmarkt 2018 Buchhandel"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Bereits vor 2 Monaten hat Brian Hibbs seine allj\u00e4hrliche Betrachtung des Comicmarktes im US Buchhandel <a rel=\"noreferrer noopener\" aria-label=\"ver\u00f6ffentlicht (\u00f6ffnet in neuem Tab)\" href=\"https:\/\/www.comicsbeat.com\/tilting-at-windmills-274-looking-at-bookscan-for-2018\/\" target=\"_blank\">ver\u00f6ffentlicht<\/a>. Er ist Inhaber eines <a rel=\"noopener noreferrer\" href=\"https:\/\/www.comixexperience.com\/\" target=\"_blank\">Comic Shops<\/a> in San Francisco und Experte auf dem Gebiet. Seine Analyse ist extrem umfangreich und detailliert und es gab einige \u00c4nderungen zum <a href=\"https:\/\/nerdenthum.de\/index.php\/2018\/07\/19\/der-us-comicmarkt-2017-buchhandel\/\">letzten Jahr<\/a> was mich dazu bewog meine Grafiken nochmal komplett zu \u00fcberarbeiten. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Brian Hibbs bezieht seine Zahlen aus dem &#8222;Bookscan&#8220; Report.Hier werden die tats\u00e4chlichen Verk\u00e4ufe an Endkunden von vielen Buchh\u00e4ndlern aufgezeichnet und der Rest hochgerechnet. Es ist wohl das genaueste System seiner Art.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><a href=\"https:\/\/nerdenthum.de\/wp-content\/uploads\/2019\/07\/BSUnits.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"690\" src=\"http:\/\/nerdenthum.de\/wp-content\/uploads\/2019\/07\/BSUnits-1024x690.jpg\" alt=\"\" class=\"wp-image-21764\" srcset=\"https:\/\/nerdenthum.de\/wp-content\/uploads\/2019\/07\/BSUnits-1024x690.jpg 1024w, https:\/\/nerdenthum.de\/wp-content\/uploads\/2019\/07\/BSUnits-300x202.jpg 300w, https:\/\/nerdenthum.de\/wp-content\/uploads\/2019\/07\/BSUnits-768x517.jpg 768w, https:\/\/nerdenthum.de\/wp-content\/uploads\/2019\/07\/BSUnits.jpg 1134w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption>Buchhandel 2018 Einheiten<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Da, was die Einheiten betrifft, Mangas in 2008 von einem so hohen Wert kamen (\u00fcber 10 Millionen verkaufte Einheiten) habe ich das abgeschnitten damit man die Ver\u00e4nderungen in den letzen Jahren noch gut erkennen kann. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zudem habe ich einige Verlage mehr aufgenommen, das liegt prim\u00e4r daran das die hier die gro\u00dfen Ver\u00e4nderungen statt gefunden haben. Die Verlage die vormals nicht so viele Comics abgesetzt haben, haben genau hier ihre Palette erweitert und das mit Erfolg.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bei Manga macht diese Aufteilung wenig Sinn, da Viz hier immer noch der absolute Platzhirsch ist und hier dann auch prim\u00e4r die Serie <a rel=\"noreferrer noopener\" aria-label=\"My Hero Academia (\u00f6ffnet in neuem Tab)\" href=\"https:\/\/de.wikipedia.org\/wiki\/My_Hero_Academia\" target=\"_blank\">My Hero Academia<\/a>. Jeder 5. verkaufte Manga geh\u00f6rt zu dieser Serie. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bei den &#8222;westlichen&#8220; Verlagen (also jene aus Europa und den USA) ist nun schon im 4. Jahr <strong>Scholastic<\/strong>. Hier sind aber weder die Verk\u00e4ufe direkt an die Endkunden \u00fcber die &#8222;Scholastic Book Fairs&#8220; noch jene an Schulen dabei. Im wesentlichen tr\u00e4gt hier &#8222;Dog Man&#8220; von <a rel=\"noreferrer noopener\" aria-label=\"Dav Pilkey (\u00f6ffnet in neuem Tab)\" href=\"https:\/\/de.wikipedia.org\/wiki\/Dav_Pilkey\" target=\"_blank\">Dav Pilkey<\/a> oder auch sein &#8222;<em>Ook and Gluk<\/em>&#8220; zum Absatz bei und das zeigt schon das eben auch Kinder in den USA Comics lesen, nur eben keine Superhelden. Aber auch hoch politische Themen wie <a rel=\"noreferrer noopener\" aria-label=\"&quot;Ein neues Land&quot; (\u00f6ffnet in neuem Tab)\" href=\"https:\/\/www.carlsen.de\/softcover\/ein-neues-land\/62282\" target=\"_blank\">&#8222;Ein neues Land&#8220;<\/a> von Shaun Tan oder die B\u00fccher von  Raina Telgemeier die sich eher an junge weibliche Leser richten spielen hier eine Rolle. Insgesamt ist es aber eine wesentlich breitere Palette die hier zum Tragen kommt. Wen das genau interessiert sollte sich Hibbs Bericht genauer anschauen. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auf dem zweiten Platz ist nun <strong>Andrews McMeel<\/strong> der prim\u00e4r Zeitungsstrips wie &#8222;Big Nate&#8220; (<a rel=\"noreferrer noopener\" aria-label=\"Super Nick (\u00f6ffnet in neuem Tab)\" href=\"https:\/\/de.wikipedia.org\/wiki\/Super_Nick\" target=\"_blank\">Super Nick<\/a>) oder <em>Phoebe and her Unicorn<\/em> (<a rel=\"noreferrer noopener\" aria-label=\"Fibi und ihr Einhorn (\u00f6ffnet in neuem Tab)\" href=\"https:\/\/de.wikipedia.org\/wiki\/Fibi_und_ihr_Einhorn\" target=\"_blank\">Fibi und ihr Einhorn<\/a>) aber auch Klassiker wie <a rel=\"noreferrer noopener\" aria-label=\"Calvin &amp; Hobbs (\u00f6ffnet in neuem Tab)\" href=\"https:\/\/de.wikipedia.org\/wiki\/Calvin_und_Hobbes\" target=\"_blank\">Calvin &amp; Hobbs<\/a> sowie &#8222;<a rel=\"noreferrer noopener\" aria-label=\"The Far Side (\u00f6ffnet in neuem Tab)\" href=\"https:\/\/de.wikipedia.org\/wiki\/The_Far_Side\" target=\"_blank\">The Far Side<\/a>&#8220; verlegt und damit eben auch Erfolge erzieht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auf dem dritten Platz folgt nun der erste &#8222;traditionelle&#8220; Buchverlag. <strong>Penguin Random House<\/strong> hat so viele verschiedene &#8222;Labels&#8220; und somit eine extrem breite Palette an Comics das es schwer ist die alle aufzuz\u00e4hlen. Das geht von Mari Andrews&#8216; &#8222;<em>Am I There Yet?: The Loop-de-loop, Zigzagging Journey to Adulthood<\/em>&#8220; bis hin zu Garfield.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auch die Nummer vier, Holtzbrink ist einer der gro\u00dfen traditionellen Verlage mit unz\u00e4hligen Sublabels. Hier finden wir dann die Comics zu &#8222;<a rel=\"noreferrer noopener\" aria-label=\"Adventure Zone (\u00f6ffnet in neuem Tab)\" href=\"https:\/\/en.wikipedia.org\/wiki\/The_Adventure_Zone#Graphic_Novel_adaptations\" target=\"_blank\">Adventure Zone<\/a>&#8220; aber auch diverse B\u00fccher von <a rel=\"noreferrer noopener\" aria-label=\"Hope Larson (\u00f6ffnet in neuem Tab)\" href=\"https:\/\/en.wikipedia.org\/wiki\/Hope_Larson\" target=\"_blank\">Hope Larson<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Als letztes kommt dann noch mit <strong>HarperCollins<\/strong> die Nummer f\u00fcnf hinzu. Hier sind die Top Seller Positively Izzy und Invisible Emmie von Terri Libenson sowie B\u00fccher des Minecraft Youtubers  <a href=\"https:\/\/www.youtube.com\/user\/PopularMMOs?hl=de&amp;gl=DE\">PopularMMO<\/a>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Erst danach folgt mit <strong>Image<\/strong> der erste traditionelle &#8222;nur Comics&#8220; Verlag, den man eben auch aus dem Fachhandel kennt. Die k\u00f6nnen trotz einem Einbruch noch immer Platz 6 halten. Das liegt auch nur an Saga und Monstress.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wie man oben an der Grafik sehen kann sind es eben gerade diese Verlage die neben Mangas Zuw\u00e4chse verzeichnen k\u00f6nnen und das mit extrem diversen Titeln. Dabei muss man auch noch ber\u00fccksichtigen das der Einbruch bei <strong>Simon &amp; Schuster<\/strong> (S&amp;S in der Grafik) nicht durch schw\u00e4chere Verk\u00e4ufe kommt, sondern dadurch das Hibbs Sachen wie &#8222;Gregs Tagebuch&#8220;, die mehr B\u00fccher mit Illustrationen sind, nicht mehr mit z\u00e4hlt. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Marvel<\/strong> kann sich knapp halten was an Titeln wie Infinity Gauntlet, Infinity War und Black Panther von Ta-Nehisi Coates liegt. Doch hier ist tats\u00e4chlich immer noch die Frage warum bei diesen erfolgreichen Filmen die letztes Jahr im Kino waren nicht mehr m\u00f6glich ist. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der gro\u00dfe Schock kommt wenn wir uns <strong>DC<\/strong> anschauen. Der Absatz ist \u00fcber 30 % eingebrochen und das ist heftig. Dies scheint prim\u00e4r an dem ver\u00e4ndern des &#8222;Brandings&#8220; von New 52 auf Rebirth zu liegen, aber auch Titel wie Watchmen die davon nicht betroffen sind brechen ein. Offensichtlich funktioniert die R\u00fcckkehr zu &#8222;alt hergebrachtem&#8220; im Buchhandel nicht so gut wie im Fachmarkt. <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><a href=\"https:\/\/nerdenthum.de\/wp-content\/uploads\/2019\/07\/BSDollar.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"http:\/\/nerdenthum.de\/wp-content\/uploads\/2019\/07\/BSDollar-1024x512.jpg\" alt=\"\" class=\"wp-image-21766\" srcset=\"https:\/\/nerdenthum.de\/wp-content\/uploads\/2019\/07\/BSDollar-1024x512.jpg 1024w, https:\/\/nerdenthum.de\/wp-content\/uploads\/2019\/07\/BSDollar-300x150.jpg 300w, https:\/\/nerdenthum.de\/wp-content\/uploads\/2019\/07\/BSDollar-768x384.jpg 768w, https:\/\/nerdenthum.de\/wp-content\/uploads\/2019\/07\/BSDollar.jpg 1134w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Der Umsatz spiegelt grob den Absatz wieder wobei Marvel hier aufgrund der h\u00f6heren Preise etwas zulegen kann. Auch hier sind es die Verlage die deutlich auf Diversit\u00e4t setzen, Comics f\u00fcr alle Altersgruppen, Geschlechter und sonstige Ausrichtungen bringen die zulegen k\u00f6nnen. In der Summe ist das ein gutes Zeichen f\u00fcr den Buchhandel. Dort etablieren sich Comics jetzt mehr und werden dadurch auch seri\u00f6ser, egal ob als bildende Unterhaltung f\u00fcr Kinder oder politischer Kommentar f\u00fcr Erwachsene.<br><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><a href=\"https:\/\/nerdenthum.de\/wp-content\/uploads\/2019\/07\/AllTPB.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"706\" src=\"http:\/\/nerdenthum.de\/wp-content\/uploads\/2019\/07\/AllTPB-1024x706.jpg\" alt=\"\" class=\"wp-image-21767\" srcset=\"https:\/\/nerdenthum.de\/wp-content\/uploads\/2019\/07\/AllTPB-1024x706.jpg 1024w, https:\/\/nerdenthum.de\/wp-content\/uploads\/2019\/07\/AllTPB-300x207.jpg 300w, https:\/\/nerdenthum.de\/wp-content\/uploads\/2019\/07\/AllTPB-768x530.jpg 768w, https:\/\/nerdenthum.de\/wp-content\/uploads\/2019\/07\/AllTPB.jpg 1134w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Nehmen wir jetzt noch die im Fachhandel abgesetzten Sammelb\u00e4nde hinzu wird das Bild eindeutiger. Manga bleibt absoluter Spitzenreiter und trotz der Tatsache das ich die gr\u00f6\u00dferen Buchhandels Verlage raus gerechnet habe sind die restlichen immer noch in Summe vor allen anderen. Der Comicmarkt stellt sich hier offensichtlich breiter auf, was eine gute Sache ist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Marvel und DC k\u00f6nnen davon nicht profitieren was in Summe wohl daran liegt das die beiden Verlage ihre Versuche sich breiter aufzustellen nicht konsequent genug durchsetzten oder am Markt platzieren konnten. Scholastic hat sie erreicht und liegt damit weit vor Image das ebenfalls stark eingebrochen ist. \u00dcber die Idee das Image eine bessere &#8222;Qualit\u00e4t&#8220; an Comics liefert l\u00e4sst sich trefflich diskutieren, dar\u00fcber sich dies nicht in mehr Verk\u00e4ufe umsetzen l\u00e4sst offensichtlich nicht.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><a href=\"https:\/\/nerdenthum.de\/wp-content\/uploads\/2019\/07\/Total.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"487\" src=\"http:\/\/nerdenthum.de\/wp-content\/uploads\/2019\/07\/Total-1024x487.jpg\" alt=\"\" class=\"wp-image-21771\" srcset=\"https:\/\/nerdenthum.de\/wp-content\/uploads\/2019\/07\/Total-1024x487.jpg 1024w, https:\/\/nerdenthum.de\/wp-content\/uploads\/2019\/07\/Total-300x143.jpg 300w, https:\/\/nerdenthum.de\/wp-content\/uploads\/2019\/07\/Total-768x366.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">In der Summe (also mit dem Verkauf der Einzelhefte) ist Marvel noch vorne und auch der Einbruch ist gestoppt. Trotz allen Unkenrufen ist das &#8222;Haus der Ideen&#8220; in den USA noch unangefochten die Kraft wenn es um Comics geht. DC bricht ein, was wohl an dem oben beschriebenen &#8222;Rebirth&#8220; Effekt liegt der starke Auswirkungen im Buchhandel hat. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gut zu sehen ist hier der rapide Anstieg der restlichen Verlage die im Buchhandel f\u00fcr Zuwach sorgen. Das ist ein deutliches Anzeichen f\u00fcr einen Paradigmenwechsel weg vom Fachhandel dessen Kundschaft letztendlich doch sehr monolithisch ist. Hierbei ist es egal ob die Leute Marvel, DC oder Image kaufen, es sind doch \u00fcberwiegend wei\u00dfe M\u00e4nner mittleren Alters. Die breitere Kundschaft tendiert eher zum Buchhandel, wo man eine viel breitere Palette an Angeboten hat. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wie sich das in den USA weiter entwickeln wird ist schwer zu sagen. Vielleicht kann der Fachhandel aus dieser Entwicklung lernen und gerade mehr auf Diversit\u00e4t setzten, dann k\u00f6nnten auch die breiteren Angebote von Marvel und DC, die ja durchaus in Anf\u00e4ngen vorhanden sind, auf ein gr\u00f6\u00dferes Publikum sto\u00dfen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bereits vor 2 Monaten hat Brian Hibbs seine allj\u00e4hrliche Betrachtung des Comicmarktes im US Buchhandel ver\u00f6ffentlicht. Er ist Inhaber eines Comic Shops in San Francisco und Experte auf dem Gebiet. Seine Analyse ist extrem umfangreich und detailliert und es gab einige \u00c4nderungen zum letzten Jahr was mich dazu bewog meine Grafiken nochmal komplett zu \u00fcberarbeiten. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21764,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[16],"tags":[1318,305],"class_list":["post-21762","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-comics-eng","tag-bookscan","tag-us-markt","post_format-post-format-image"],"_links":{"self":[{"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/posts\/21762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/comments?post=21762"}],"version-history":[{"count":6,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/posts\/21762\/revisions"}],"predecessor-version":[{"id":21777,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/posts\/21762\/revisions\/21777"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/media\/21764"}],"wp:attachment":[{"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/media?parent=21762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/categories?post=21762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/tags?post=21762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}