{"id":24577,"date":"2020-03-12T17:00:00","date_gmt":"2020-03-12T16:00:00","guid":{"rendered":"http:\/\/nerdenthum.de\/?p=24577"},"modified":"2020-03-11T14:55:13","modified_gmt":"2020-03-11T13:55:13","slug":"livezig-die-online-messe","status":"publish","type":"post","link":"https:\/\/nerdenthum.de\/index.php\/2020\/03\/12\/livezig-die-online-messe\/","title":{"rendered":"LIVEzig die Online Messe"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/nerdenthum.de\/wp-content\/uploads\/2020\/03\/LIVEzigLOGO.jpg\" alt=\"\" class=\"wp-image-24578\" srcset=\"https:\/\/nerdenthum.de\/wp-content\/uploads\/2020\/03\/LIVEzigLOGO.jpg 400w, https:\/\/nerdenthum.de\/wp-content\/uploads\/2020\/03\/LIVEzigLOGO-300x300.jpg 300w, https:\/\/nerdenthum.de\/wp-content\/uploads\/2020\/03\/LIVEzigLOGO-150x150.jpg 150w, https:\/\/nerdenthum.de\/wp-content\/uploads\/2020\/03\/LIVEzigLOGO-200x200.jpg 200w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Die Buchmesse in Leipzig wurde abgesagt, und somit leider auch die Manga-Comic-Con die seit 2014 zeitgleich dort statt findet. Das wollten aber einige Comicschaffende nicht auf sich sitzen lassen und so wurde die <a href=\"http:\/\/www.comicsolidarity.de\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"LIVEzig (\u00f6ffnet in neuem Tab)\">LIVEzig<\/a> ins Leben gerufen, eine Online Messe mit hochkar\u00e4tiger Besetzung.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ralf Singh, Sch\u00f6pfer von &#8222;Zinnober&#8220; und Autor und Kolorist von &#8222;The Impure&#8220; hat als Organisator ein tolles Programm mit Streams auf die Beine gestellt und hochkar\u00e4tige Partner gefunden. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reinschauen lohnt sich auf Alle F\u00e4lle.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Buchmesse in Leipzig wurde abgesagt, und somit leider auch die Manga-Comic-Con die seit 2014 zeitgleich dort statt findet. Das wollten aber einige Comicschaffende nicht auf sich sitzen lassen und so wurde die LIVEzig ins Leben gerufen, eine Online Messe mit hochkar\u00e4tiger Besetzung. Ralf Singh, Sch\u00f6pfer von &#8222;Zinnober&#8220; und Autor und Kolorist von &#8222;The Impure&#8220; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":24578,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[121],"tags":[3063,1795,2742,1801],"class_list":["post-24577","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comics-deu","tag-livezig","tag-ralf-singh","tag-the-impure","tag-zinnober"],"_links":{"self":[{"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/posts\/24577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/comments?post=24577"}],"version-history":[{"count":1,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/posts\/24577\/revisions"}],"predecessor-version":[{"id":24579,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/posts\/24577\/revisions\/24579"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/media\/24578"}],"wp:attachment":[{"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/media?parent=24577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/categories?post=24577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/tags?post=24577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}