{"id":29669,"date":"2022-01-14T12:00:00","date_gmt":"2022-01-14T11:00:00","guid":{"rendered":"https:\/\/nerdenthum.de\/?p=29669"},"modified":"2022-01-12T15:50:29","modified_gmt":"2022-01-12T14:50:29","slug":"justice-league-33-deu","status":"publish","type":"post","link":"https:\/\/nerdenthum.de\/index.php\/2022\/01\/14\/justice-league-33-deu\/","title":{"rendered":"Justice League #33 [deu]"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignright size-full is-resized\"><a href=\"https:\/\/nerdenthum.de\/wp-content\/uploads\/2022\/01\/justice-league-33-future-state-djulea033-cover.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/nerdenthum.de\/wp-content\/uploads\/2022\/01\/justice-league-33-future-state-djulea033-cover.jpg\" alt=\"\" class=\"wp-image-29670\" width=\"392\" height=\"600\" srcset=\"https:\/\/nerdenthum.de\/wp-content\/uploads\/2022\/01\/justice-league-33-future-state-djulea033-cover.jpg 523w, https:\/\/nerdenthum.de\/wp-content\/uploads\/2022\/01\/justice-league-33-future-state-djulea033-cover-196x300.jpg 196w\" sizes=\"auto, (max-width: 392px) 100vw, 392px\" \/><\/a><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Der Kampf gegen den Hyperclan und Merlin<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Autor:<\/strong> Joshua Williamson, Ram V<br><strong>Zeichner:<\/strong> Robson Rocha, Marcio Takara<br><strong>Tusche:<\/strong> Daniel Henriques,  Marcio Takara <br><strong>Farben:<\/strong> Romulo Fajardo Jr., Marcelo Maiolo<br><strong>Lettering:<\/strong> Walproject<br><strong>\u00dcbersetzung:<\/strong> Christian Heiss<br><strong>Kaufen:<\/strong> <a rel=\"noreferrer noopener\" href=\"https:\/\/paninishop.de\/justice-league-superhelden-comics\/justice-league-2019-33-future-state-djulea033\" target=\"_blank\">Panini Shop<\/a><br><strong>Erscheinungsdatum:<\/strong> 07.12.2021<br><strong>Bewertung:<\/strong> 4\/5<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Die neue Justice League wurde vom Hyperclan \u00fcberrascht und in die selbe Dimension verbannt wo auch die wei\u00dfen Marsianer gefangen gehalten wurden. Nun hei\u00dft es nicht nur entkommen sondern auch planen wie man den \u00fcberm\u00e4chtig scheinenden Gegner besiegen kann.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Art wie die neue Justice League zusammen gekommen ist und was mit der alten passiert ist wird hier n\u00e4her beleuchtet und damit der Basis f\u00fcr die Entwicklung der Charaktere gelegt die hier tats\u00e4chlich besser funktioniert als im Heft zuvor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zeichnerisch gut umgesetzt vom leider viel zu fr\u00fch verstorbenen Robson Rocha.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der zweite Teil der sich um den magischen Teil der Justice League dreht beginnt meiner einer l\u00e4ngeren Erkl\u00e4rung was mit Dr. Fate passiert ist und geht dann in einen Kampf \u00fcber der zeigt wie wenig Chancen die verbliebenen Magienutzer gegen Merlin haben. Nicht ganz so zufriedenstellend wie der erste Teil und mit einem extrem offenen Ende das wohl nie aufgegriffen wird. <\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Der Kampf gegen den Hyperclan und Merlin Autor: Joshua Williamson, Ram VZeichner: Robson Rocha, Marcio TakaraTusche: Daniel Henriques, Marcio Takara Farben: Romulo Fajardo Jr., Marcelo MaioloLettering: Walproject\u00dcbersetzung: Christian HeissKaufen: Panini ShopErscheinungsdatum: 07.12.2021Bewertung: 4\/5<\/p>\n","protected":false},"author":1,"featured_media":29670,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[121],"tags":[1109,3571,982,605,1287,9,2332,970,135,359],"class_list":["post-29669","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-comics-deu","tag-daniel-henriques","tag-future-state","tag-joshua-williamson","tag-marcelo-maiolo","tag-marcio-takara","tag-panini","tag-ram-v","tag-robson-rocha","tag-romulo-fajardo-jr","tag-walproject","post_format-post-format-image"],"_links":{"self":[{"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/posts\/29669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/comments?post=29669"}],"version-history":[{"count":1,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/posts\/29669\/revisions"}],"predecessor-version":[{"id":29671,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/posts\/29669\/revisions\/29671"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/media\/29670"}],"wp:attachment":[{"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/media?parent=29669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/categories?post=29669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/tags?post=29669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}