{"id":32327,"date":"2023-04-04T14:00:00","date_gmt":"2023-04-04T12:00:00","guid":{"rendered":"https:\/\/nerdenthum.de\/?p=32327"},"modified":"2023-05-10T20:00:07","modified_gmt":"2023-05-10T18:00:07","slug":"nocterra-1-deu","status":"publish","type":"post","link":"https:\/\/nerdenthum.de\/index.php\/2023\/04\/04\/nocterra-1-deu\/","title":{"rendered":"Nocterra 1 [deu]"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignright size-full is-resized\"><a href=\"https:\/\/i0.wp.com\/nerdenthum.de\/wp-content\/uploads\/2023\/04\/Nocterra.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/nerdenthum.de\/wp-content\/uploads\/2023\/04\/Nocterra.jpg?resize=450%2C695&#038;ssl=1\" alt=\"\" class=\"wp-image-32328\" width=\"450\" height=\"695\" srcset=\"https:\/\/i0.wp.com\/nerdenthum.de\/wp-content\/uploads\/2023\/04\/Nocterra.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/nerdenthum.de\/wp-content\/uploads\/2023\/04\/Nocterra.jpg?resize=194%2C300&amp;ssl=1 194w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p>Ewige Nacht<\/p>\n\n\n\n<p><strong>Autor:<\/strong> Scott Snyder<br><strong>Zeichner<\/strong>: Tony S. Daniel<br><strong>Farben:<\/strong> Tomeu Morey<br><strong>Letterer:<\/strong> Barbara M\u00fcller<br><strong>\u00dcbersetzung:<\/strong> Stefan Pannor<br><strong>Kaufen:<\/strong> <a rel=\"noreferrer noopener\" href=\"https:\/\/www.cross-cult.de\/titel\/nocterra-1-mit-vollgas-in-die-dunkelheit.html?titel_medium=9\" target=\"_blank\">Cross Cult<\/a><br><strong>Erscheinungsdatum:<\/strong> 27.02.2023<br><strong>Bewertung:<\/strong> 4\/5<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Ein schreckliches Ereignis hat die Erde in Dunkelheit geh\u00fcllt und alles was dieser Dunkelheit zu lange ausgesetzt ist verwandelt sich in ein schreckliches Monster, Tiere, Pflanzen und nat\u00fcrlich auch Menschen. <\/p>\n\n\n\n<p>Sundog ist in dieser Dunkelheit die Fahrerin eines LKWs der zwischen den verbliebenen Enklaven der Menschen verkehrt und immer auf der Suche nach starken Lichtquellen da nur diese die Dunkelheit zur\u00fcck halten k\u00f6nnen und sogar solche wieder heilen k\u00f6nnen die im ersten Stadium der Infektion sind.  Doch dann nimmt sie die falschen Passagiere mit und wird gejagt.<\/p>\n\n\n\n<p>Wenn sich das liest wie die Mischung auf diversen anderen Serien mit ner geh\u00f6rigen Portion Walking Dead dann liegt das wohl daran das es sehr schwer etwas vollkommen neues zu erschaffen. Sp\u00e4testens als man die Herkunft der Dunkelheit erf\u00e4hrt f\u00fchlt man sich an eine andere Reihe (die ebenfalls bei Cross-Cult erscheint) erinnert. Das steigert das Gef\u00fchl des wilden Mischens von Ideen noch mehr, bis zu dem Punkt wo man merkt das vieles zwar bekannt ist, die Charaktere und die Motivation dahinter einen dennoch fesselt. Man will auch mehr \u00fcber die Hintergr\u00fcnde erfahren wie alles so gekommen ist wie es aktuell ist und warum einige Leute so extrem b\u00f6sartig handeln. <\/p>\n\n\n\n<p>Das Tony S. Daniel das dann auch noch klasse in Szene setzt wundert nicht mehr. Viel wichtiger ist jedoch das Tomeu Morey bei den Farben und Effekten brilliert. In eine Welt die von Dunkelheit gepr\u00e4gt ist spielt das Licht eben eine herausragende Rolle. Das Zusammenspiel zwischen dieser brutalen Dunkelheit, den Schattenwesen und dem &#8222;erl\u00f6senden&#8220; Licht ist gelungen und es wird ein Horror ganz eigener Art erzeugt.<\/p>\n\n\n\n<p>[Rezensionsexemplar zur Verf\u00fcgung gestellt von Cross Cult]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ewige Nacht Autor: Scott SnyderZeichner: Tony S. DanielFarben: Tomeu MoreyLetterer: Barbara M\u00fcller\u00dcbersetzung: Stefan PannorKaufen: Cross CultErscheinungsdatum: 27.02.2023Bewertung: 4\/5<\/p>\n","protected":false},"author":1,"featured_media":32328,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[121],"tags":[3822,2608,3941,235,1370,1117,1115],"class_list":["post-32327","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-comics-deu","tag-barbara-mueller","tag-cross-cult","tag-nocterra","tag-scott-snyder","tag-stefan-pannor","tag-tomeu-morey","tag-tony-s-daniel","post_format-post-format-image"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/nerdenthum.de\/wp-content\/uploads\/2023\/04\/Nocterra.jpg?fit=600%2C926&ssl=1","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/posts\/32327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/comments?post=32327"}],"version-history":[{"count":2,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/posts\/32327\/revisions"}],"predecessor-version":[{"id":32339,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/posts\/32327\/revisions\/32339"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/media\/32328"}],"wp:attachment":[{"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/media?parent=32327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/categories?post=32327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/tags?post=32327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}