{"id":9252,"date":"2017-03-30T09:00:15","date_gmt":"2017-03-30T07:00:15","guid":{"rendered":"http:\/\/nerdenthum.de\/?p=9252"},"modified":"2017-03-30T13:06:43","modified_gmt":"2017-03-30T11:06:43","slug":"swamp-thing-1-deu","status":"publish","type":"post","link":"https:\/\/nerdenthum.de\/index.php\/2017\/03\/30\/swamp-thing-1-deu\/","title":{"rendered":"Swamp Thing #1 [deu]"},"content":{"rendered":"<p>Nur durch die Nostalgiebrille zu ertragen.<\/p>\n<p><a href=\"http:\/\/nerdenthum.de\/wp-content\/uploads\/2017\/03\/SWAMPTHING_Softcover_760.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/nerdenthum.de\/wp-content\/uploads\/2017\/03\/SWAMPTHING_Softcover_760-197x300.jpg\" alt=\"\" width=\"197\" height=\"300\" class=\"alignright size-medium wp-image-9253\" srcset=\"https:\/\/nerdenthum.de\/wp-content\/uploads\/2017\/03\/SWAMPTHING_Softcover_760-197x300.jpg 197w, https:\/\/nerdenthum.de\/wp-content\/uploads\/2017\/03\/SWAMPTHING_Softcover_760.jpg 493w\" sizes=\"auto, (max-width: 197px) 100vw, 197px\" \/><\/a><\/p>\n<p><strong>Autor:<\/strong> Len Wein<br \/>\n<strong>Zeichner:<\/strong> Kelley Jones<br \/>\n<strong>Colorist:<\/strong> Michelle Madsen<br \/>\n<strong>Letterer:<\/strong> Astarte Design<br \/>\n<strong>\u00dcbersetzung:<\/strong> Josef Rother<br \/>\n<strong>Kaufen:<\/strong> <a href=\"https:\/\/www.paninishop.de\/artikel\/swamp-thing\" target=\"_blank\">Panini Shop<\/a><br \/>\n<strong>Bewertung:<\/strong> 1\/5<\/p>\n<p><!--more--><\/p>\n<p>Swamp Thing ist der Comic mit dem Alan Moore sich einen Namen gemacht hat. Seine Ideen, die Art zu schreiben, der eher subtile Horror und die Charakterisierungen waren damals schon genial und sind immer noch unerreicht. Das man jetzt versucht daraus Kapital zu schlagen ist durchaus verst\u00e4ndlich, das man den Erfinder der Figur, Len Wein, daran setzt ebenso. Leider geht das in meinen Augen nicht wirklich auf.<\/p>\n<p>Vor Moore war Swamp Thing ein sehr dr\u00f6ges und gew\u00f6hnliches Horrorcomic. Ein gutes, keine Frage, aber eben nichts besonderes. Selbst Marty Pasko, der vor Moore die Figur schrieb und eine Menge sozialkritische und sogar Umwelt-Themen mit rein brachte konnte nicht wirklich die Tiefe erreichen die Moore geschaffen hat. Was Wein hier allerdings schreibt ist Nostalgie pur und das meine ich leider auf extrem schlechte Art und Weise. Man bekommt eine Zombie Story die nicht nur gew\u00f6hnlich sondern auch vorhersehbar ist und danach wirds noch schlimmer. Das Wein Matthew Cable wieder holt ist schon seltsam genug, hatte der doch unter Moore schon eine bewegte Geschichte, das er dann aber auch noch jemand die Macht von Swamp Thing missbrauchen l\u00e4sst, inkl. der Tatsache das man sich in einem Dorf in den S\u00fcmpfen verschanzt und seine Forderungen \u00fcber Reportern mit Kameras verbreiten l\u00e4sst kam so 1:1 in Moores Swamp Thing vor und auch die Aufl\u00f6sung wer hinter allem steckt und wie er das bewerkstelligt hat hatten wir so schon mal.<\/p>\n<p>Wenn ich eine Geschichte neu lese und die sich wie eine Kopie liest erwarte ich zumindest neue Impulse oder neue Kleinigkeiten die Charaktere oder Geschichte in einem neuen Licht da stehen lassen, das fehlt hier v\u00f6llig.<\/p>\n<p>Was den Band ein wenig besser macht sind die Zeichnungen von Kelley Jones der mir prim\u00e4r mit seinen &#8222;Over the Top&#8220; Darstellungen von Batman in Erinnerung aber hier macht er seine Sache f\u00fcr die Umst\u00e4nde recht gut. Es ist ein Horrorcomics was er auch so dar stellt. Da kann man als Routinier auch nicht so viel falsch machen. <\/p>\n<p>Alles in Allem sehr entt\u00e4uschend.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nur durch die Nostalgiebrille zu ertragen. Autor: Len Wein Zeichner: Kelley Jones Colorist: Michelle Madsen Letterer: Astarte Design \u00dcbersetzung: Josef Rother Kaufen: Panini Shop Bewertung: 1\/5<\/p>\n","protected":false},"author":1,"featured_media":9253,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[121],"tags":[29,481,396,979,743,988,980,9,987],"class_list":["post-9252","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-comics-deu","tag-alan-moore","tag-astarte-design","tag-josef-rother","tag-kelley-jones","tag-len-wein","tag-martin-pasko","tag-michelle-madsen","tag-panini","tag-swamp-thing","post_format-post-format-image"],"_links":{"self":[{"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/posts\/9252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/comments?post=9252"}],"version-history":[{"count":6,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/posts\/9252\/revisions"}],"predecessor-version":[{"id":9279,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/posts\/9252\/revisions\/9279"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/media\/9253"}],"wp:attachment":[{"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/media?parent=9252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/categories?post=9252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nerdenthum.de\/index.php\/wp-json\/wp\/v2\/tags?post=9252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}